{"id":2795,"date":"2024-05-07T09:06:48","date_gmt":"2024-05-07T07:06:48","guid":{"rendered":"https:\/\/www.metal-expert.com\/prodotto\/poste-con-fijacion-al-suelo-5\/"},"modified":"2024-05-07T09:06:48","modified_gmt":"2024-05-07T07:06:48","slug":"poste-con-fijacion-al-suelo-5","status":"publish","type":"prodotto","link":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/","title":{"rendered":"Poste con fijaci\u00f3n al suelo"},"content":{"rendered":"<p>Poste de tubo de acero inoxidable AISI 304 satinado de 42,4\u00d72,0 mm de di\u00e1metro y 1000 mm de altura. Completo con 4 soportes de 90\u00b0 para vidrio de 8,76 \u00f3 10,76 mm de espesor, anclaje para fijaci\u00f3n a suelo con embellecedor. Apto para uso en interiores o exteriores en entornos no agresivos.<\/p>\n","protected":false},"featured_media":2796,"template":"","meta":{"prodotto_sottotitolo":"Con 4 soportes de vidrio de 90\u00b0 8,76-10,76 mm","prodotto_codice":"EC24204P90M","prodotto_tipologia":"semilavorato","prodotto_materiale":"inox","prodotto_installazione":"pavimento","prodotto_caratteristiche":{"prodotto_caratteristiche-esterni":"true","prodotto_caratteristiche-interni":"true","prodotto_caratteristiche-aggressivi":"false"},"prodotto_video-tutorial-etichetta":"Video Tutorial","prodotto_video-tutorial":"","prodotto_video-tutorial2-etichetta":"Video Tutorial"},"categoria-prodotto":[79,84],"class_list":["post-2795","prodotto","type-prodotto","status-publish","has-post-thumbnail","hentry","categoria-prodotto-parapetos-y-barandillas","categoria-prodotto-barandillas-con-vidrio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poste con fijaci\u00f3n al suelo - Metal Expert<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poste con fijaci\u00f3n al suelo - Metal Expert\" \/>\n<meta property=\"og:description\" content=\"Poste de tubo de acero inoxidable AISI 304 satinado de 42,4\u00d72,0 mm de di\u00e1metro y 1000 mm de altura. Completo con 4 soportes de 90\u00b0 para vidrio de 8,76 \u00f3 10,76 mm de espesor, anclaje para fijaci\u00f3n a suelo con embellecedor. Apto para uso en interiores o exteriores en entornos no agresivos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Metal Expert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/poste-con-fijacion-al-suelo-5\\\/\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/poste-con-fijacion-al-suelo-5\\\/\",\"name\":\"Poste con fijaci\u00f3n al suelo - Metal Expert\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/poste-con-fijacion-al-suelo-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/poste-con-fijacion-al-suelo-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/EC24204P90.jpg\",\"datePublished\":\"2024-05-07T07:06:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/poste-con-fijacion-al-suelo-5\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/poste-con-fijacion-al-suelo-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/poste-con-fijacion-al-suelo-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/EC24204P90.jpg\",\"contentUrl\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/EC24204P90.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/poste-con-fijacion-al-suelo-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Poste con fijaci\u00f3n al suelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/\",\"name\":\"Metal Expert\",\"description\":\"Prodotti in ferro e acciaio inox per la distribuzione moderna\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#organization\",\"name\":\"Metal Expert\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/metalexpert-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/metalexpert-logo.svg\",\"width\":127,\"height\":50,\"caption\":\"Metal Expert\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poste con fijaci\u00f3n al suelo - Metal Expert","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/","og_locale":"es_ES","og_type":"article","og_title":"Poste con fijaci\u00f3n al suelo - Metal Expert","og_description":"Poste de tubo de acero inoxidable AISI 304 satinado de 42,4\u00d72,0 mm de di\u00e1metro y 1000 mm de altura. Completo con 4 soportes de 90\u00b0 para vidrio de 8,76 \u00f3 10,76 mm de espesor, anclaje para fijaci\u00f3n a suelo con embellecedor. Apto para uso en interiores o exteriores en entornos no agresivos.","og_url":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/","og_site_name":"Metal Expert","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/","url":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/","name":"Poste con fijaci\u00f3n al suelo - Metal Expert","isPartOf":{"@id":"https:\/\/www.metal-expert.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/#primaryimage"},"image":{"@id":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/05\/EC24204P90.jpg","datePublished":"2024-05-07T07:06:48+00:00","breadcrumb":{"@id":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/#primaryimage","url":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/05\/EC24204P90.jpg","contentUrl":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/05\/EC24204P90.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.metal-expert.com\/es\/producto\/poste-con-fijacion-al-suelo-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.metal-expert.com\/es\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.metal-expert.com\/es\/producto\/"},{"@type":"ListItem","position":3,"name":"Poste con fijaci\u00f3n al suelo"}]},{"@type":"WebSite","@id":"https:\/\/www.metal-expert.com\/es\/#website","url":"https:\/\/www.metal-expert.com\/es\/","name":"Metal Expert","description":"Prodotti in ferro e acciaio inox per la distribuzione moderna","publisher":{"@id":"https:\/\/www.metal-expert.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metal-expert.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.metal-expert.com\/es\/#organization","name":"Metal Expert","url":"https:\/\/www.metal-expert.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.metal-expert.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/03\/metalexpert-logo.svg","contentUrl":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/03\/metalexpert-logo.svg","width":127,"height":50,"caption":"Metal Expert"},"image":{"@id":"https:\/\/www.metal-expert.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/prodotto\/2795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/prodotto"}],"about":[{"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/types\/prodotto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/media\/2796"}],"wp:attachment":[{"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/media?parent=2795"}],"wp:term":[{"taxonomy":"categoria-prodotto","embeddable":true,"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/categoria-prodotto?post=2795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}