{"id":2707,"date":"2024-05-06T11:49:28","date_gmt":"2024-05-06T09:49:28","guid":{"rendered":"https:\/\/www.metal-expert.com\/prodotto\/anclaje-de-pared-2\/"},"modified":"2024-05-06T11:49:28","modified_gmt":"2024-05-06T09:49:28","slug":"anclaje-de-pared-2","status":"publish","type":"prodotto","link":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/","title":{"rendered":"Anclaje de pared"},"content":{"rendered":"<p>Elemento de acero inoxidable AISI 304 satinado para el anclaje<br \/>\na pared de un tubo de 42,4 mm de di\u00e1metro. Tornillos de<br \/>\nfijaci\u00f3n no incluidos. Apto para uso en interiores o exteriores en<br \/>\nambientes no agresivos.<\/p>\n","protected":false},"featured_media":2708,"template":"","meta":{"prodotto_sottotitolo":"Para tubo de di\u00e1metro 42,4x2 mm","prodotto_codice":"E2070\/304M","prodotto_tipologia":"semilavorato","prodotto_materiale":"inox","prodotto_installazione":"","prodotto_caratteristiche":{"prodotto_caratteristiche-esterni":"true","prodotto_caratteristiche-interni":"true","prodotto_caratteristiche-aggressivi":"false"},"prodotto_video-tutorial-etichetta":"Video Tutorial","prodotto_video-tutorial":"","prodotto_video-tutorial2-etichetta":"Video Tutorial"},"categoria-prodotto":[79,84,83,82],"class_list":["post-2707","prodotto","type-prodotto","status-publish","has-post-thumbnail","hentry","categoria-prodotto-parapetos-y-barandillas","categoria-prodotto-barandillas-con-vidrio","categoria-prodotto-barandillas-con-varilla","categoria-prodotto-barandillas-de-cable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anclaje de pared - Metal Expert<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anclaje de pared - Metal Expert\" \/>\n<meta property=\"og:description\" content=\"Elemento de acero inoxidable AISI 304 satinado para el anclaje a pared de un tubo de 42,4 mm de di\u00e1metro. Tornillos de fijaci\u00f3n no incluidos. Apto para uso en interiores o exteriores en ambientes no agresivos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Metal Expert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/anclaje-de-pared-2\\\/\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/anclaje-de-pared-2\\\/\",\"name\":\"Anclaje de pared - Metal Expert\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/anclaje-de-pared-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/anclaje-de-pared-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/E2070_304.jpg\",\"datePublished\":\"2024-05-06T09:49:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/anclaje-de-pared-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/anclaje-de-pared-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/anclaje-de-pared-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/E2070_304.jpg\",\"contentUrl\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/E2070_304.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/anclaje-de-pared-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anclaje de pared\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/\",\"name\":\"Metal Expert\",\"description\":\"Prodotti in ferro e acciaio inox per la distribuzione moderna\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#organization\",\"name\":\"Metal Expert\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/metalexpert-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.metal-expert.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/metalexpert-logo.svg\",\"width\":127,\"height\":50,\"caption\":\"Metal Expert\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metal-expert.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anclaje de pared - Metal Expert","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/","og_locale":"es_ES","og_type":"article","og_title":"Anclaje de pared - Metal Expert","og_description":"Elemento de acero inoxidable AISI 304 satinado para el anclaje a pared de un tubo de 42,4 mm de di\u00e1metro. Tornillos de fijaci\u00f3n no incluidos. Apto para uso en interiores o exteriores en ambientes no agresivos.","og_url":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/","og_site_name":"Metal Expert","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/","url":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/","name":"Anclaje de pared - Metal Expert","isPartOf":{"@id":"https:\/\/www.metal-expert.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/#primaryimage"},"image":{"@id":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/05\/E2070_304.jpg","datePublished":"2024-05-06T09:49:28+00:00","breadcrumb":{"@id":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/#primaryimage","url":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/05\/E2070_304.jpg","contentUrl":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/05\/E2070_304.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.metal-expert.com\/es\/producto\/anclaje-de-pared-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.metal-expert.com\/es\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.metal-expert.com\/es\/producto\/"},{"@type":"ListItem","position":3,"name":"Anclaje de pared"}]},{"@type":"WebSite","@id":"https:\/\/www.metal-expert.com\/es\/#website","url":"https:\/\/www.metal-expert.com\/es\/","name":"Metal Expert","description":"Prodotti in ferro e acciaio inox per la distribuzione moderna","publisher":{"@id":"https:\/\/www.metal-expert.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metal-expert.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.metal-expert.com\/es\/#organization","name":"Metal Expert","url":"https:\/\/www.metal-expert.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.metal-expert.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/03\/metalexpert-logo.svg","contentUrl":"https:\/\/www.metal-expert.com\/wp-content\/uploads\/2024\/03\/metalexpert-logo.svg","width":127,"height":50,"caption":"Metal Expert"},"image":{"@id":"https:\/\/www.metal-expert.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/prodotto\/2707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/prodotto"}],"about":[{"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/types\/prodotto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/media\/2708"}],"wp:attachment":[{"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/media?parent=2707"}],"wp:term":[{"taxonomy":"categoria-prodotto","embeddable":true,"href":"https:\/\/www.metal-expert.com\/es\/wp-json\/wp\/v2\/categoria-prodotto?post=2707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}